{"id":2646,"date":"2025-03-12T12:20:13","date_gmt":"2025-03-12T12:20:13","guid":{"rendered":"https:\/\/jeco-energies.com\/oplossing\/guarantee\/"},"modified":"2025-08-18T06:45:19","modified_gmt":"2025-08-18T06:45:19","slug":"guarantee","status":"publish","type":"oplossing","link":"https:\/\/jeco-energies.com\/en\/solution\/guarantee\/","title":{"rendered":"Guarantee"},"content":{"rendered":"","protected":false},"featured_media":2263,"menu_order":15,"template":"","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-2646","oplossing","type-oplossing","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guarantee &#8211; Jeco Energies<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jeco-energies.com\/en\/solution\/guarantee\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guarantee &#8211; Jeco Energies\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jeco-energies.com\/en\/solution\/guarantee\/\" \/>\n<meta property=\"og:site_name\" content=\"Jeco Energies\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-18T06:45:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jeco-energies.com\/wp-content\/uploads\/2025\/03\/Jeco_Energies_expertises_garanderen_alpha_edit_2_2768b91189.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"444\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/en\\\/solution\\\/guarantee\\\/\",\"url\":\"https:\\\/\\\/jeco-energies.com\\\/en\\\/solution\\\/guarantee\\\/\",\"name\":\"Guarantee &#8211; Jeco Energies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/en\\\/solution\\\/guarantee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/en\\\/solution\\\/guarantee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jeco-energies.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Jeco_Energies_expertises_garanderen_alpha_edit_2_2768b91189.jpeg\",\"datePublished\":\"2025-03-12T12:20:13+00:00\",\"dateModified\":\"2025-08-18T06:45:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/en\\\/solution\\\/guarantee\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jeco-energies.com\\\/en\\\/solution\\\/guarantee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/en\\\/solution\\\/guarantee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jeco-energies.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Jeco_Energies_expertises_garanderen_alpha_edit_2_2768b91189.jpeg\",\"contentUrl\":\"https:\\\/\\\/jeco-energies.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Jeco_Energies_expertises_garanderen_alpha_edit_2_2768b91189.jpeg\",\"width\":444,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/en\\\/solution\\\/guarantee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jeco-energies.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guarantee\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/jeco-energies.com\\\/en\\\/\",\"name\":\"Jeco Energies\",\"description\":\"When Power Becomes Smart\",\"publisher\":{\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jeco-energies.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/en\\\/#organization\",\"name\":\"Jeco Energies\",\"alternateName\":\"Jeco\",\"url\":\"https:\\\/\\\/jeco-energies.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jeco-energies.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo_Jeco_Web.png\",\"contentUrl\":\"https:\\\/\\\/jeco-energies.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo_Jeco_Web.png\",\"width\":339,\"height\":136,\"caption\":\"Jeco Energies\"},\"image\":{\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guarantee &#8211; Jeco Energies","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jeco-energies.com\/en\/solution\/guarantee\/","og_locale":"en_US","og_type":"article","og_title":"Guarantee &#8211; Jeco Energies","og_url":"https:\/\/jeco-energies.com\/en\/solution\/guarantee\/","og_site_name":"Jeco Energies","article_modified_time":"2025-08-18T06:45:19+00:00","og_image":[{"width":444,"height":250,"url":"https:\/\/jeco-energies.com\/wp-content\/uploads\/2025\/03\/Jeco_Energies_expertises_garanderen_alpha_edit_2_2768b91189.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jeco-energies.com\/en\/solution\/guarantee\/","url":"https:\/\/jeco-energies.com\/en\/solution\/guarantee\/","name":"Guarantee &#8211; Jeco Energies","isPartOf":{"@id":"https:\/\/jeco-energies.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jeco-energies.com\/en\/solution\/guarantee\/#primaryimage"},"image":{"@id":"https:\/\/jeco-energies.com\/en\/solution\/guarantee\/#primaryimage"},"thumbnailUrl":"https:\/\/jeco-energies.com\/wp-content\/uploads\/2025\/03\/Jeco_Energies_expertises_garanderen_alpha_edit_2_2768b91189.jpeg","datePublished":"2025-03-12T12:20:13+00:00","dateModified":"2025-08-18T06:45:19+00:00","breadcrumb":{"@id":"https:\/\/jeco-energies.com\/en\/solution\/guarantee\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jeco-energies.com\/en\/solution\/guarantee\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jeco-energies.com\/en\/solution\/guarantee\/#primaryimage","url":"https:\/\/jeco-energies.com\/wp-content\/uploads\/2025\/03\/Jeco_Energies_expertises_garanderen_alpha_edit_2_2768b91189.jpeg","contentUrl":"https:\/\/jeco-energies.com\/wp-content\/uploads\/2025\/03\/Jeco_Energies_expertises_garanderen_alpha_edit_2_2768b91189.jpeg","width":444,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/jeco-energies.com\/en\/solution\/guarantee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jeco-energies.com\/en\/"},{"@type":"ListItem","position":2,"name":"Guarantee"}]},{"@type":"WebSite","@id":"https:\/\/jeco-energies.com\/en\/#website","url":"https:\/\/jeco-energies.com\/en\/","name":"Jeco Energies","description":"When Power Becomes Smart","publisher":{"@id":"https:\/\/jeco-energies.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jeco-energies.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/jeco-energies.com\/en\/#organization","name":"Jeco Energies","alternateName":"Jeco","url":"https:\/\/jeco-energies.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jeco-energies.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/jeco-energies.com\/wp-content\/uploads\/2024\/04\/Logo_Jeco_Web.png","contentUrl":"https:\/\/jeco-energies.com\/wp-content\/uploads\/2024\/04\/Logo_Jeco_Web.png","width":339,"height":136,"caption":"Jeco Energies"},"image":{"@id":"https:\/\/jeco-energies.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/jeco-energies.com\/en\/wp-json\/wp\/v2\/oplossing\/2646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jeco-energies.com\/en\/wp-json\/wp\/v2\/oplossing"}],"about":[{"href":"https:\/\/jeco-energies.com\/en\/wp-json\/wp\/v2\/types\/oplossing"}],"version-history":[{"count":0,"href":"https:\/\/jeco-energies.com\/en\/wp-json\/wp\/v2\/oplossing\/2646\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jeco-energies.com\/en\/wp-json\/wp\/v2\/media\/2263"}],"wp:attachment":[{"href":"https:\/\/jeco-energies.com\/en\/wp-json\/wp\/v2\/media?parent=2646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}