{"id":3665,"date":"2025-03-14T12:44:31","date_gmt":"2025-03-14T12:44:31","guid":{"rendered":"https:\/\/jeco-energies.com\/expertises\/mittel-und-hochspannung\/"},"modified":"2025-10-29T14:56:57","modified_gmt":"2025-10-29T14:56:57","slug":"mittel-und-hochspannung","status":"publish","type":"expertises","link":"https:\/\/jeco-energies.com\/de\/expertises\/energie\/mittel-und-hochspannung\/","title":{"rendered":"Mittel- und Hochspannung"},"content":{"rendered":"","protected":false},"featured_media":3672,"parent":3695,"menu_order":98,"template":"","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categorie":[19],"class_list":["post-3665","expertises","type-expertises","status-publish","has-post-thumbnail","hentry","categorie-energy"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mittel- und Hochspannung &#8211; Jeco Energies<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jeco-energies.com\/de\/expertises\/energie\/mittel-und-hochspannung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mittel- und Hochspannung &#8211; Jeco Energies\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jeco-energies.com\/de\/expertises\/energie\/mittel-und-hochspannung\/\" \/>\n<meta property=\"og:site_name\" content=\"Jeco Energies\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-29T14:56:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jeco-energies.com\/wp-content\/uploads\/2025\/03\/180405_zidis_hoboken_congo_MS_cellen_0329_9e8a930d12-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1258\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/de\\\/expertises\\\/energie\\\/mittel-und-hochspannung\\\/\",\"url\":\"https:\\\/\\\/jeco-energies.com\\\/de\\\/expertises\\\/energie\\\/mittel-und-hochspannung\\\/\",\"name\":\"Mittel- und Hochspannung &#8211; Jeco Energies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/de\\\/expertises\\\/energie\\\/mittel-und-hochspannung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/de\\\/expertises\\\/energie\\\/mittel-und-hochspannung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jeco-energies.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/180405_zidis_hoboken_congo_MS_cellen_0329_9e8a930d12-1.jpeg\",\"datePublished\":\"2025-03-14T12:44:31+00:00\",\"dateModified\":\"2025-10-29T14:56:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/de\\\/expertises\\\/energie\\\/mittel-und-hochspannung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jeco-energies.com\\\/de\\\/expertises\\\/energie\\\/mittel-und-hochspannung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/de\\\/expertises\\\/energie\\\/mittel-und-hochspannung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jeco-energies.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/180405_zidis_hoboken_congo_MS_cellen_0329_9e8a930d12-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/jeco-energies.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/180405_zidis_hoboken_congo_MS_cellen_0329_9e8a930d12-1.jpeg\",\"width\":2000,\"height\":1258},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/de\\\/expertises\\\/energie\\\/mittel-und-hochspannung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jeco-energies.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Energy\",\"item\":\"https:\\\/\\\/jeco-energies.com\\\/categorie\\\/energy\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Energie\",\"item\":\"https:\\\/\\\/jeco-energies.com\\\/de\\\/expertises\\\/energy\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Mittel- und Hochspannung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/jeco-energies.com\\\/de\\\/\",\"name\":\"Jeco Energies\",\"description\":\"When Power Becomes Smart\",\"publisher\":{\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jeco-energies.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/de\\\/#organization\",\"name\":\"Jeco Energies\",\"alternateName\":\"Jeco\",\"url\":\"https:\\\/\\\/jeco-energies.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jeco-energies.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo_Jeco_Web.png\",\"contentUrl\":\"https:\\\/\\\/jeco-energies.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo_Jeco_Web.png\",\"width\":339,\"height\":136,\"caption\":\"Jeco Energies\"},\"image\":{\"@id\":\"https:\\\/\\\/jeco-energies.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mittel- und Hochspannung &#8211; Jeco Energies","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jeco-energies.com\/de\/expertises\/energie\/mittel-und-hochspannung\/","og_locale":"de_DE","og_type":"article","og_title":"Mittel- und Hochspannung &#8211; Jeco Energies","og_url":"https:\/\/jeco-energies.com\/de\/expertises\/energie\/mittel-und-hochspannung\/","og_site_name":"Jeco Energies","article_modified_time":"2025-10-29T14:56:57+00:00","og_image":[{"width":2000,"height":1258,"url":"https:\/\/jeco-energies.com\/wp-content\/uploads\/2025\/03\/180405_zidis_hoboken_congo_MS_cellen_0329_9e8a930d12-1.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jeco-energies.com\/de\/expertises\/energie\/mittel-und-hochspannung\/","url":"https:\/\/jeco-energies.com\/de\/expertises\/energie\/mittel-und-hochspannung\/","name":"Mittel- und Hochspannung &#8211; Jeco Energies","isPartOf":{"@id":"https:\/\/jeco-energies.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jeco-energies.com\/de\/expertises\/energie\/mittel-und-hochspannung\/#primaryimage"},"image":{"@id":"https:\/\/jeco-energies.com\/de\/expertises\/energie\/mittel-und-hochspannung\/#primaryimage"},"thumbnailUrl":"https:\/\/jeco-energies.com\/wp-content\/uploads\/2025\/03\/180405_zidis_hoboken_congo_MS_cellen_0329_9e8a930d12-1.jpeg","datePublished":"2025-03-14T12:44:31+00:00","dateModified":"2025-10-29T14:56:57+00:00","breadcrumb":{"@id":"https:\/\/jeco-energies.com\/de\/expertises\/energie\/mittel-und-hochspannung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jeco-energies.com\/de\/expertises\/energie\/mittel-und-hochspannung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/jeco-energies.com\/de\/expertises\/energie\/mittel-und-hochspannung\/#primaryimage","url":"https:\/\/jeco-energies.com\/wp-content\/uploads\/2025\/03\/180405_zidis_hoboken_congo_MS_cellen_0329_9e8a930d12-1.jpeg","contentUrl":"https:\/\/jeco-energies.com\/wp-content\/uploads\/2025\/03\/180405_zidis_hoboken_congo_MS_cellen_0329_9e8a930d12-1.jpeg","width":2000,"height":1258},{"@type":"BreadcrumbList","@id":"https:\/\/jeco-energies.com\/de\/expertises\/energie\/mittel-und-hochspannung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jeco-energies.com\/de\/"},{"@type":"ListItem","position":2,"name":"Energy","item":"https:\/\/jeco-energies.com\/categorie\/energy\/"},{"@type":"ListItem","position":3,"name":"Energie","item":"https:\/\/jeco-energies.com\/de\/expertises\/energy\/"},{"@type":"ListItem","position":4,"name":"Mittel- und Hochspannung"}]},{"@type":"WebSite","@id":"https:\/\/jeco-energies.com\/de\/#website","url":"https:\/\/jeco-energies.com\/de\/","name":"Jeco Energies","description":"When Power Becomes Smart","publisher":{"@id":"https:\/\/jeco-energies.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jeco-energies.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/jeco-energies.com\/de\/#organization","name":"Jeco Energies","alternateName":"Jeco","url":"https:\/\/jeco-energies.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/jeco-energies.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/jeco-energies.com\/wp-content\/uploads\/2024\/04\/Logo_Jeco_Web.png","contentUrl":"https:\/\/jeco-energies.com\/wp-content\/uploads\/2024\/04\/Logo_Jeco_Web.png","width":339,"height":136,"caption":"Jeco Energies"},"image":{"@id":"https:\/\/jeco-energies.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/jeco-energies.com\/de\/wp-json\/wp\/v2\/expertises\/3665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jeco-energies.com\/de\/wp-json\/wp\/v2\/expertises"}],"about":[{"href":"https:\/\/jeco-energies.com\/de\/wp-json\/wp\/v2\/types\/expertises"}],"version-history":[{"count":0,"href":"https:\/\/jeco-energies.com\/de\/wp-json\/wp\/v2\/expertises\/3665\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/jeco-energies.com\/de\/wp-json\/wp\/v2\/expertises\/3695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jeco-energies.com\/de\/wp-json\/wp\/v2\/media\/3672"}],"wp:attachment":[{"href":"https:\/\/jeco-energies.com\/de\/wp-json\/wp\/v2\/media?parent=3665"}],"wp:term":[{"taxonomy":"categorie","embeddable":true,"href":"https:\/\/jeco-energies.com\/de\/wp-json\/wp\/v2\/categorie?post=3665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}